{"id":18048,"date":"2024-04-01T17:26:26","date_gmt":"2024-04-01T21:26:26","guid":{"rendered":"https:\/\/simeontrust.org\/dona\/"},"modified":"2026-01-30T12:33:43","modified_gmt":"2026-01-30T17:33:43","slug":"dona-2","status":"publish","type":"page","link":"https:\/\/simeontrust.org\/it\/dona-2\/","title":{"rendered":"Dona"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/tpl-give.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-18048","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dona - Charles Simeon Trust<\/title>\n<meta name=\"description\" content=\"Donazioni attraverso Carte di Credito o Bonifici Automatici (ACH) possono essere versate in sicurezza attraverso il tasto sottostante. Gli assegni possono essere intestati alla Charles Simeon Trust e spediti alll&#039;indirizzo sottostante. Donare attraverso assegni o uno dei seguenti metodi, ci aiuta ad evitare costose spese di elaborazione. Le donazioni possono essere dirette da fondazioni o fondi consigliati dai donatori. Per donare tramite bonifico bancario nazionale, inviare un&#039;e-mail a info@simeontrust.org per le informazioni sul nostro account Per offrire titoli apprezzati (azioni, obbligazioni, fondi comuni di investimento), inviare un&#039;e-mail a info@simeontrust.org per le informazioni sul nostro account. Le donazioni di titoli apprezzati possono attualmente essere accettate dalla Charles Simeon Trust solo negli Stati Uniti. Se sei interessato a fare una donazione pianificata o patrimoniale, invia un&#039;e-mail a info@simeontrust.org per fissare un appuntamento per discutere i tuoi obiettivi filantropici con un membro del nostro team. Anche i residenti negli Stati Uniti potrebbero trovare utile questa Brochure sulla Pianificazione di Doni e Patrimoni. La Charles Simeon Trust \u00e8 un&#039;organizzazione no-profit 501(c)3 negli Stati Uniti (dal 2001) e il nostro numero di identificazione fiscale federale \u00e8 36-7342471. La Charles Simeon Trust \u00e8 un ente di beneficenza registrato in Canada (dal 2016). Le donazioni sono deducibili dalle tasse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/simeontrust.org\/it\/dona-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dona - Charles Simeon Trust\" \/>\n<meta property=\"og:description\" content=\"Donazioni attraverso Carte di Credito o Bonifici Automatici (ACH) possono essere versate in sicurezza attraverso il tasto sottostante. Gli assegni possono essere intestati alla Charles Simeon Trust e spediti alll&#039;indirizzo sottostante. Donare attraverso assegni o uno dei seguenti metodi, ci aiuta ad evitare costose spese di elaborazione. Le donazioni possono essere dirette da fondazioni o fondi consigliati dai donatori. Per donare tramite bonifico bancario nazionale, inviare un&#039;e-mail a info@simeontrust.org per le informazioni sul nostro account Per offrire titoli apprezzati (azioni, obbligazioni, fondi comuni di investimento), inviare un&#039;e-mail a info@simeontrust.org per le informazioni sul nostro account. Le donazioni di titoli apprezzati possono attualmente essere accettate dalla Charles Simeon Trust solo negli Stati Uniti. Se sei interessato a fare una donazione pianificata o patrimoniale, invia un&#039;e-mail a info@simeontrust.org per fissare un appuntamento per discutere i tuoi obiettivi filantropici con un membro del nostro team. Anche i residenti negli Stati Uniti potrebbero trovare utile questa Brochure sulla Pianificazione di Doni e Patrimoni. La Charles Simeon Trust \u00e8 un&#039;organizzazione no-profit 501(c)3 negli Stati Uniti (dal 2001) e il nostro numero di identificazione fiscale federale \u00e8 36-7342471. La Charles Simeon Trust \u00e8 un ente di beneficenza registrato in Canada (dal 2016). Le donazioni sono deducibili dalle tasse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/simeontrust.org\/it\/dona-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Charles Simeon Trust\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T17:33:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/simeontrust.org\\\/it\\\/dona-2\\\/\",\"url\":\"https:\\\/\\\/simeontrust.org\\\/it\\\/dona-2\\\/\",\"name\":\"Dona - Charles Simeon Trust\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/simeontrust.org\\\/#website\"},\"datePublished\":\"2024-04-01T21:26:26+00:00\",\"dateModified\":\"2026-01-30T17:33:43+00:00\",\"description\":\"Donazioni attraverso Carte di Credito o Bonifici Automatici (ACH) possono essere versate in sicurezza attraverso il tasto sottostante. Gli assegni possono essere intestati alla Charles Simeon Trust e spediti alll'indirizzo sottostante. Donare attraverso assegni o uno dei seguenti metodi, ci aiuta ad evitare costose spese di elaborazione. Le donazioni possono essere dirette da fondazioni o fondi consigliati dai donatori. Per donare tramite bonifico bancario nazionale, inviare un'e-mail a info@simeontrust.org per le informazioni sul nostro account Per offrire titoli apprezzati (azioni, obbligazioni, fondi comuni di investimento), inviare un'e-mail a info@simeontrust.org per le informazioni sul nostro account. Le donazioni di titoli apprezzati possono attualmente essere accettate dalla Charles Simeon Trust solo negli Stati Uniti. Se sei interessato a fare una donazione pianificata o patrimoniale, invia un'e-mail a info@simeontrust.org per fissare un appuntamento per discutere i tuoi obiettivi filantropici con un membro del nostro team. Anche i residenti negli Stati Uniti potrebbero trovare utile questa Brochure sulla Pianificazione di Doni e Patrimoni. La Charles Simeon Trust \u00e8 un'organizzazione no-profit 501(c)3 negli Stati Uniti (dal 2001) e il nostro numero di identificazione fiscale federale \u00e8 36-7342471. La Charles Simeon Trust \u00e8 un ente di beneficenza registrato in Canada (dal 2016). Le donazioni sono deducibili dalle tasse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/simeontrust.org\\\/it\\\/dona-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/simeontrust.org\\\/it\\\/dona-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/simeontrust.org\\\/it\\\/dona-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/simeontrust.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/simeontrust.org\\\/#website\",\"url\":\"https:\\\/\\\/simeontrust.org\\\/\",\"name\":\"Simeon Trust\",\"description\":\"Training the next generation of Bible expositors.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/simeontrust.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dona - Charles Simeon Trust","description":"Donazioni attraverso Carte di Credito o Bonifici Automatici (ACH) possono essere versate in sicurezza attraverso il tasto sottostante. Gli assegni possono essere intestati alla Charles Simeon Trust e spediti alll'indirizzo sottostante. Donare attraverso assegni o uno dei seguenti metodi, ci aiuta ad evitare costose spese di elaborazione. Le donazioni possono essere dirette da fondazioni o fondi consigliati dai donatori. Per donare tramite bonifico bancario nazionale, inviare un'e-mail a info@simeontrust.org per le informazioni sul nostro account Per offrire titoli apprezzati (azioni, obbligazioni, fondi comuni di investimento), inviare un'e-mail a info@simeontrust.org per le informazioni sul nostro account. Le donazioni di titoli apprezzati possono attualmente essere accettate dalla Charles Simeon Trust solo negli Stati Uniti. Se sei interessato a fare una donazione pianificata o patrimoniale, invia un'e-mail a info@simeontrust.org per fissare un appuntamento per discutere i tuoi obiettivi filantropici con un membro del nostro team. Anche i residenti negli Stati Uniti potrebbero trovare utile questa Brochure sulla Pianificazione di Doni e Patrimoni. La Charles Simeon Trust \u00e8 un'organizzazione no-profit 501(c)3 negli Stati Uniti (dal 2001) e il nostro numero di identificazione fiscale federale \u00e8 36-7342471. La Charles Simeon Trust \u00e8 un ente di beneficenza registrato in Canada (dal 2016). Le donazioni sono deducibili dalle tasse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/simeontrust.org\/it\/dona-2\/","og_locale":"it_IT","og_type":"article","og_title":"Dona - Charles Simeon Trust","og_description":"Donazioni attraverso Carte di Credito o Bonifici Automatici (ACH) possono essere versate in sicurezza attraverso il tasto sottostante. Gli assegni possono essere intestati alla Charles Simeon Trust e spediti alll'indirizzo sottostante. Donare attraverso assegni o uno dei seguenti metodi, ci aiuta ad evitare costose spese di elaborazione. Le donazioni possono essere dirette da fondazioni o fondi consigliati dai donatori. Per donare tramite bonifico bancario nazionale, inviare un'e-mail a info@simeontrust.org per le informazioni sul nostro account Per offrire titoli apprezzati (azioni, obbligazioni, fondi comuni di investimento), inviare un'e-mail a info@simeontrust.org per le informazioni sul nostro account. Le donazioni di titoli apprezzati possono attualmente essere accettate dalla Charles Simeon Trust solo negli Stati Uniti. Se sei interessato a fare una donazione pianificata o patrimoniale, invia un'e-mail a info@simeontrust.org per fissare un appuntamento per discutere i tuoi obiettivi filantropici con un membro del nostro team. Anche i residenti negli Stati Uniti potrebbero trovare utile questa Brochure sulla Pianificazione di Doni e Patrimoni. La Charles Simeon Trust \u00e8 un'organizzazione no-profit 501(c)3 negli Stati Uniti (dal 2001) e il nostro numero di identificazione fiscale federale \u00e8 36-7342471. La Charles Simeon Trust \u00e8 un ente di beneficenza registrato in Canada (dal 2016). Le donazioni sono deducibili dalle tasse.","og_url":"https:\/\/simeontrust.org\/it\/dona-2\/","og_site_name":"Charles Simeon Trust","article_modified_time":"2026-01-30T17:33:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/simeontrust.org\/it\/dona-2\/","url":"https:\/\/simeontrust.org\/it\/dona-2\/","name":"Dona - Charles Simeon Trust","isPartOf":{"@id":"https:\/\/simeontrust.org\/#website"},"datePublished":"2024-04-01T21:26:26+00:00","dateModified":"2026-01-30T17:33:43+00:00","description":"Donazioni attraverso Carte di Credito o Bonifici Automatici (ACH) possono essere versate in sicurezza attraverso il tasto sottostante. Gli assegni possono essere intestati alla Charles Simeon Trust e spediti alll'indirizzo sottostante. Donare attraverso assegni o uno dei seguenti metodi, ci aiuta ad evitare costose spese di elaborazione. Le donazioni possono essere dirette da fondazioni o fondi consigliati dai donatori. Per donare tramite bonifico bancario nazionale, inviare un'e-mail a info@simeontrust.org per le informazioni sul nostro account Per offrire titoli apprezzati (azioni, obbligazioni, fondi comuni di investimento), inviare un'e-mail a info@simeontrust.org per le informazioni sul nostro account. Le donazioni di titoli apprezzati possono attualmente essere accettate dalla Charles Simeon Trust solo negli Stati Uniti. Se sei interessato a fare una donazione pianificata o patrimoniale, invia un'e-mail a info@simeontrust.org per fissare un appuntamento per discutere i tuoi obiettivi filantropici con un membro del nostro team. Anche i residenti negli Stati Uniti potrebbero trovare utile questa Brochure sulla Pianificazione di Doni e Patrimoni. La Charles Simeon Trust \u00e8 un'organizzazione no-profit 501(c)3 negli Stati Uniti (dal 2001) e il nostro numero di identificazione fiscale federale \u00e8 36-7342471. La Charles Simeon Trust \u00e8 un ente di beneficenza registrato in Canada (dal 2016). Le donazioni sono deducibili dalle tasse.","breadcrumb":{"@id":"https:\/\/simeontrust.org\/it\/dona-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/simeontrust.org\/it\/dona-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/simeontrust.org\/it\/dona-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/simeontrust.org\/it\/"},{"@type":"ListItem","position":2,"name":"Dona"}]},{"@type":"WebSite","@id":"https:\/\/simeontrust.org\/#website","url":"https:\/\/simeontrust.org\/","name":"Simeon Trust","description":"Training the next generation of Bible expositors.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/simeontrust.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/simeontrust.org\/it\/wp-json\/wp\/v2\/pages\/18048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simeontrust.org\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/simeontrust.org\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/simeontrust.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/simeontrust.org\/it\/wp-json\/wp\/v2\/comments?post=18048"}],"version-history":[{"count":0,"href":"https:\/\/simeontrust.org\/it\/wp-json\/wp\/v2\/pages\/18048\/revisions"}],"wp:attachment":[{"href":"https:\/\/simeontrust.org\/it\/wp-json\/wp\/v2\/media?parent=18048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}